{"id":33,"count":19,"description":"","link":"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/","name":"Cuidado cabello","slug":"cuidado-cabello","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuidado cabello archivos - Clarel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuidado cabello archivos - Clarel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/\" \/>\n<meta property=\"og:site_name\" content=\"Clarel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/\",\"url\":\"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/\",\"name\":\"Cuidado cabello archivos - Clarel\",\"isPartOf\":{\"@id\":\"https:\/\/www.clarel.mom\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.clarel.mom\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidado cabello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.clarel.mom\/blog\/#website\",\"url\":\"https:\/\/www.clarel.mom\/blog\/\",\"name\":\"Clarel\",\"description\":\"Tienda Online de perfumeria, cosmetica, maquillaje y hogar.\",\"publisher\":{\"@id\":\"https:\/\/www.clarel.mom\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.clarel.mom\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.clarel.mom\/blog\/#organization\",\"name\":\"Clarel\",\"url\":\"https:\/\/www.clarel.mom\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.clarel.mom\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/clarel-test.ezenit.link\/blog\/wp-content\/uploads\/2022\/08\/logo_clarel.png\",\"contentUrl\":\"https:\/\/clarel-test.ezenit.link\/blog\/wp-content\/uploads\/2022\/08\/logo_clarel.png\",\"width\":432,\"height\":101,\"caption\":\"Clarel\"},\"image\":{\"@id\":\"https:\/\/www.clarel.mom\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuidado cabello archivos - Clarel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/","og_locale":"es_ES","og_type":"article","og_title":"Cuidado cabello archivos - Clarel","og_url":"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/","og_site_name":"Clarel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/","url":"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/","name":"Cuidado cabello archivos - Clarel","isPartOf":{"@id":"https:\/\/www.clarel.mom\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clarel.mom\/blog\/category\/cuidado-cabello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.clarel.mom\/blog\/"},{"@type":"ListItem","position":2,"name":"Cuidado cabello"}]},{"@type":"WebSite","@id":"https:\/\/www.clarel.mom\/blog\/#website","url":"https:\/\/www.clarel.mom\/blog\/","name":"Clarel","description":"Tienda Online de perfumeria, cosmetica, maquillaje y hogar.","publisher":{"@id":"https:\/\/www.clarel.mom\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clarel.mom\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.clarel.mom\/blog\/#organization","name":"Clarel","url":"https:\/\/www.clarel.mom\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clarel.mom\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/clarel-test.ezenit.link\/blog\/wp-content\/uploads\/2022\/08\/logo_clarel.png","contentUrl":"https:\/\/clarel-test.ezenit.link\/blog\/wp-content\/uploads\/2022\/08\/logo_clarel.png","width":432,"height":101,"caption":"Clarel"},"image":{"@id":"https:\/\/www.clarel.mom\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.clarel.mom\/blog\/wp-json\/wp\/v2\/categories\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clarel.mom\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.clarel.mom\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.clarel.mom\/blog\/wp-json\/wp\/v2\/posts?categories=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}